{"id":632,"count":1,"description":"","link":"https:\/\/www.mgc.es\/ca\/blog\/tag\/envejecer\/","name":"envejecer","slug":"envejecer","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>envejecer Archives - MGC M\u00fatua<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"envejecer Archives - MGC M\u00fatua\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mgc.es\/blog\/tag\/envejecer\/\" \/>\n<meta property=\"og:site_name\" content=\"MGC M\u00fatua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mgcmutua\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"envejecer Archives - MGC M\u00fatua","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"envejecer Archives - MGC M\u00fatua","og_url":"https:\/\/www.mgc.es\/blog\/tag\/envejecer\/","og_site_name":"MGC M\u00fatua","twitter_card":"summary_large_image","twitter_site":"@mgcmutua","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.mgc.es\/blog\/tag\/envejecer\/","url":"https:\/\/www.mgc.es\/blog\/tag\/envejecer\/","name":"envejecer Archives - MGC M\u00fatua","isPartOf":{"@id":"https:\/\/www.mgc.es\/#website"},"breadcrumb":{"@id":"https:\/\/www.mgc.es\/blog\/tag\/envejecer\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mgc.es\/blog\/tag\/envejecer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mgc.es\/ca\/"},{"@type":"ListItem","position":2,"name":"envejecer"}]},{"@type":"WebSite","@id":"https:\/\/www.mgc.es\/#website","url":"https:\/\/www.mgc.es\/","name":"MGC M\u00fatua","description":"MGC M\u00fatua \u00e9s una entitat asseguradora sense \u00e0nim de lucre constitu\u00efda al 1982 i especialitzada en assegurances de salut i assist\u00e8ncia.","publisher":{"@id":"https:\/\/www.mgc.es\/#organization"},"alternateName":"MGC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mgc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.mgc.es\/#organization","name":"MGC Mutua","alternateName":"MGC","url":"https:\/\/www.mgc.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.mgc.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.mgc.es\/wp-content\/uploads\/2020\/03\/mgcmutua_h2_2t_reduccions.png","contentUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2020\/03\/mgcmutua_h2_2t_reduccions.png","width":303,"height":165,"caption":"MGC Mutua"},"image":{"@id":"https:\/\/www.mgc.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mgcmutua","https:\/\/x.com\/mgcmutua","https:\/\/www.youtube.com\/c\/MGCMutua"]}]}},"_links":{"self":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/tags\/632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts?tags=632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}