{"id":11552,"date":"2022-04-04T10:26:39","date_gmt":"2022-04-04T08:26:39","guid":{"rendered":"http:\/\/web-server-devel.mgc.es\/em-fa-mal-el-coll\/"},"modified":"2022-08-03T11:23:44","modified_gmt":"2022-08-03T09:23:44","slug":"em-fa-mal-el-coll","status":"publish","type":"post","link":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/","title":{"rendered":"Em fa mal el coll"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndex de continguts<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#Per_que_ens_fa_mal_el_coll\" >Per qu\u00e8 ens fa mal el coll?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#Quins_factors_poden_causar_mal_de_coll\" >Quins factors poden causar mal de coll?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#De_quines_malalties_pot_ser_simptoma_el_mal_de_coll\" >De quines malalties pot ser s\u00edmptoma el mal de coll?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#Com_a_processos_inflamatoris_podriem_parlar_per_exemple_de\" >Com a processos inflamatoris podr\u00edem parlar, per exemple, de:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#Com_a_processos_infecciosos_les_mes_tipiques_serien\" >Com a processos infecciosos, les m\u00e9s t\u00edpiques serien:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#Com_podem_tractar_el_mal_de_coll\" >Com podem tractar el mal de coll?<\/a><\/li><\/ul><\/nav><\/div>\n\n<div class=\"video\"><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/213861596\" allowfullscreen=\"allowfullscreen\" width=\"640\" height=\"360\" frameborder=\"0\"><\/iframe><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El mal de coll no \u00e9s una malaltia per si mateix, sin\u00f3 que \u00e9s un s\u00edmptoma d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a la faringe. Avui parlem amb el Dr. Ricard Bargu\u00e9s Cardel\u00fas, especialista en Otorinolaringologia del <a href=\"https:\/\/www.mgc.es\/clinicas\/centro-medico-mgc\/\">Centre M\u00e8dic MGC<\/a>, sobre les causes i el tractament del mal de coll.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Per_que_ens_fa_mal_el_coll\"><\/span><strong>Per qu\u00e8 ens fa mal el coll? <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Primer de tot, hem de dir que el dolor no \u00e9s una malaltia, sin\u00f3 que \u00e9s un s\u00edmptoma. \u00c9s a dir, \u00e9s un senyal d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a l\u2019\u00e0rea que sigui, en aquest cas la faringe. Cal tenir en compte que la faringe \u00e9s una estructura que est\u00e0 al fons de la boca i de la cavitat nasal. \u00c9s un tub que est\u00e0 obert per davant i que t\u00e9 una funci\u00f3 doble:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Una funci\u00f3 respirat\u00f2ria: hi passa l\u2019aire que ve del nas i que va cap als pulmons.<\/li><li>Una funci\u00f3 de pas dels aliments que venen de la boca i van cap a l\u2019est\u00f3mac. I, per tant, \u00e9s una zona molt sensible que ha de ser capa\u00e7 de digerir-los.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Quan fa mal \u00e9s que hi ha alguna patologia o algun proc\u00e9s que irrita, inflama o danya aquest territori. Hem de con\u00e8ixer, doncs, quin \u00e9s l\u2019origen del dolor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quins_factors_poden_causar_mal_de_coll\"><\/span><strong>Quins factors poden causar mal de coll?<\/strong> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pot haver-hi diferents tipus de factors: poden ser processos inflamatoris o infecciosos, ferides que s\u2019han generat en aquest territori o tumors. Tamb\u00e9 pot haver-hi el que anomenem dolors extr\u00ednsecs, \u00e9s a dir, dolors que apareixen als voltants de la zona i que quan ens empassem els aliments, els notem com a mals propis de la gola. I cada un d\u2019aquests factors t\u00e9 unes patologies o unes causes que generen dolor.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.mgc.es\/wp-content\/uploads\/2017\/04\/dolor-garganta_redu.jpg\" alt=\"\" class=\"wp-image-3327\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"De_quines_malalties_pot_ser_simptoma_el_mal_de_coll\"><\/span><strong>De quines malalties pot ser s\u00edmptoma el mal de coll?<\/strong> <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Des de petites mol\u00e8sties, com pot ser una picor que provoca tos, fins a dolors molt intensos que poden fer, fins i tot, que no puguem empassar-nos res. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Com_a_processos_inflamatoris_podriem_parlar_per_exemple_de\"><\/span>Com a processos inflamatoris podr\u00edem parlar, per exemple, de:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>La sequedat far\u00edngia de la persona que respira habitualment per la boca.<\/li><li>Processos irritatius com el reflux gastroesof\u00e0gic, que s\u00f3n les pujades d\u2019\u00e0cid de l\u2019est\u00f3mac; com que \u00e9s \u00e0cid clorh\u00eddric, crema el coll, que no est\u00e0 preparat per aguantar-ho.<\/li><li>El tabac, per exemple, \u00e9s possiblement una de les principals causes: \u00e9s un element irritant que, en passar-hi cont\u00ednuament, fa que s\u2019inflami.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Com_a_processos_infecciosos_les_mes_tipiques_serien\"><\/span>Com a processos infecciosos, les m\u00e9s t\u00edpiques serien:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Les amigdalitis, que habitualment van acompanyades de febre, amb plaques pult\u00e0cies (blanquinoses) al fons de la faringe. En un grau m\u00e9s greu, l\u2019amigdalitis pot esdevenir un absc\u00e9s periamigdal\u00ed, en qu\u00e8 es forma una borsa de pus darrere de les am\u00edgdales. Aquest proc\u00e9s requereix tractaments m\u00e9s agressius.<\/li><li>Una altra patologia de qu\u00e8 pot ser s\u00edmptoma, i que ja t\u00e9 una certa import\u00e0ncia, seria l\u2019epiglotitis, que es produeix una mica m\u00e9s avall, a l\u2019entrada de la laringe, i que pot provocar fins i tot una sensaci\u00f3 d\u2019asf\u00edxia i ofec.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9 hi ha les cremades que podem provocar a la faringe en ingerir aliments o vapors molt calents i arran de les quals, durant uns dies, sentirem aquest dolor en el moment d\u2019engolir.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/www.mgc.es\/wp-content\/uploads\/2017\/04\/fumar-redu.jpg\" alt=\"\" class=\"wp-image-3331\"\/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Una altra causa \u00e9s el que hem esmentat abans: els dolors extr\u00ednsecs. S\u00f3n dolors que es poden produir en l\u2019estructura muscular del voltant de la faringe que subjecta el cap, per una inflamaci\u00f3 d\u2019algun cart\u00edlag articular de la laringe, o de les v\u00e8rtebres. Aix\u00f2 fa que ens faci mal en engolir i que ho identifiquem com a mal de coll.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I ja com a malalties m\u00e9s greus hi hauria els tumors, que es poden originar sobretot en persones fumadores i bevedores. Aquests tumors poden provocar un dolor en empassar-se aliments que vagi augmentant al llarg del temps o, en els casos m\u00e9s greus, una dificultat per engolir o fins i tot un bloqueig complet de la degluci\u00f3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Com_podem_tractar_el_mal_de_coll\"><\/span><strong>Com podem tractar el mal de coll? <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dep\u00e8n de si \u00e9s un dolor progressiu o \u00e9s un dolor agut. En principi, si \u00e9s un dolor agut, caldria comen\u00e7ar amb analg\u00e8sics, amb calmants com ara el paracetamol o l\u2019ibuprof\u00e8n. Per\u00f2 aix\u00f2 seria per calmar el dolor al moment. L\u2019important \u00e9s que, si un dolor persisteix durant uns dies, cal consultar el metge de cap\u00e7alera o que ho vegi l\u2019otorinolaring\u00f2leg per establir-ne la causa. L\u2019especialista que correspongui dictar\u00e0 el tractament per intentar resoldre-ho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mal de coll no \u00e9s una malaltia per si mateix, sin\u00f3 que \u00e9s un s\u00edmptoma d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a la faringe.<\/p>\n","protected":false},"author":3,"featured_media":24511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[999,187,15,1],"tags":[402,413,481],"class_list":["post-11552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otorrinolaringologia","category-salud","category-salut","category-sin-categorizar","tag-centre-medic","tag-destacat","tag-prevencio"],"featured_image_src":"https:\/\/www.mgc.es\/wp-content\/uploads\/2022\/02\/007-Faringitis.jpg","author_info":{"display_name":"Revista Inter\u00e8s Mutu","author_link":"https:\/\/www.mgc.es\/ca\/blog\/author\/interesmutu\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em fa mal el coll - MGC M\u00fatua<\/title>\n<meta name=\"description\" content=\"El mal de coll no \u00e9s una malaltia per si mateix, sin\u00f3 que \u00e9s un s\u00edmptoma d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a la faringe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em fa mal el coll - MGC M\u00fatua\" \/>\n<meta property=\"og:description\" content=\"El mal de coll no \u00e9s una malaltia per si mateix, sin\u00f3 que \u00e9s un s\u00edmptoma d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a la faringe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/\" \/>\n<meta property=\"og:site_name\" content=\"MGC M\u00fatua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mgcmutua\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T08:26:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-03T09:23:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mgc.es\/wp-content\/uploads\/2022\/02\/007-Faringitis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Revista Inter\u00e8s Mutu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mgcmutua\" \/>\n<meta name=\"twitter:site\" content=\"@mgcmutua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Revista Inter\u00e8s Mutu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em fa mal el coll - MGC M\u00fatua","description":"El mal de coll no \u00e9s una malaltia per si mateix, sin\u00f3 que \u00e9s un s\u00edmptoma d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a la faringe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/","og_locale":"ca_ES","og_type":"article","og_title":"Em fa mal el coll - MGC M\u00fatua","og_description":"El mal de coll no \u00e9s una malaltia per si mateix, sin\u00f3 que \u00e9s un s\u00edmptoma d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a la faringe.","og_url":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/","og_site_name":"MGC M\u00fatua","article_publisher":"https:\/\/www.facebook.com\/mgcmutua","article_published_time":"2022-04-04T08:26:39+00:00","article_modified_time":"2022-08-03T09:23:44+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.mgc.es\/wp-content\/uploads\/2022\/02\/007-Faringitis.jpg","type":"image\/jpeg"}],"author":"Revista Inter\u00e8s Mutu","twitter_card":"summary_large_image","twitter_creator":"@mgcmutua","twitter_site":"@mgcmutua","twitter_misc":{"Escrit per":"Revista Inter\u00e8s Mutu","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#article","isPartOf":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/"},"author":{"name":"Revista Inter\u00e8s Mutu","@id":"https:\/\/www.mgc.es\/#\/schema\/person\/332e205b874bf159e39fea54cd137ab6"},"headline":"Em fa mal el coll","datePublished":"2022-04-04T08:26:39+00:00","dateModified":"2022-08-03T09:23:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/"},"wordCount":798,"commentCount":0,"publisher":{"@id":"https:\/\/www.mgc.es\/#organization"},"image":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2022\/02\/007-Faringitis.jpg","keywords":["centre m\u00e8dic","destacat","prevenci\u00f3"],"articleSection":["Otorrinolaringologia","Salud y medicina","Salut i medicina","Sin categorizar"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/","url":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/","name":"Em fa mal el coll - MGC M\u00fatua","isPartOf":{"@id":"https:\/\/www.mgc.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#primaryimage"},"image":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2022\/02\/007-Faringitis.jpg","datePublished":"2022-04-04T08:26:39+00:00","dateModified":"2022-08-03T09:23:44+00:00","description":"El mal de coll no \u00e9s una malaltia per si mateix, sin\u00f3 que \u00e9s un s\u00edmptoma d\u2019alerta que ens avisa que alguna cosa no est\u00e0 funcionant b\u00e9 a la faringe.","breadcrumb":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#primaryimage","url":"https:\/\/www.mgc.es\/wp-content\/uploads\/2022\/02\/007-Faringitis.jpg","contentUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2022\/02\/007-Faringitis.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.mgc.es\/ca\/blog\/em-fa-mal-el-coll\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mgc.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Em fa mal el coll"}]},{"@type":"WebSite","@id":"https:\/\/www.mgc.es\/#website","url":"https:\/\/www.mgc.es\/","name":"MGC M\u00fatua","description":"MGC M\u00fatua \u00e9s una entitat asseguradora sense \u00e0nim de lucre constitu\u00efda al 1982 i especialitzada en assegurances de salut i assist\u00e8ncia.","publisher":{"@id":"https:\/\/www.mgc.es\/#organization"},"alternateName":"MGC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mgc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.mgc.es\/#organization","name":"MGC Mutua","alternateName":"MGC","url":"https:\/\/www.mgc.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.mgc.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.mgc.es\/wp-content\/uploads\/2020\/03\/mgcmutua_h2_2t_reduccions.png","contentUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2020\/03\/mgcmutua_h2_2t_reduccions.png","width":303,"height":165,"caption":"MGC Mutua"},"image":{"@id":"https:\/\/www.mgc.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mgcmutua","https:\/\/x.com\/mgcmutua","https:\/\/www.youtube.com\/c\/MGCMutua"]},{"@type":"Person","@id":"https:\/\/www.mgc.es\/#\/schema\/person\/332e205b874bf159e39fea54cd137ab6","name":"Revista Inter\u00e8s Mutu","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/52302d684339b9d7bf5691e2ad00835d62ce3b4a435f21ca9f21fbe39c63cb1b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52302d684339b9d7bf5691e2ad00835d62ce3b4a435f21ca9f21fbe39c63cb1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52302d684339b9d7bf5691e2ad00835d62ce3b4a435f21ca9f21fbe39c63cb1b?s=96&d=mm&r=g","caption":"Revista Inter\u00e8s Mutu"}}]}},"_links":{"self":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts\/11552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/comments?post=11552"}],"version-history":[{"count":5,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts\/11552\/revisions"}],"predecessor-version":[{"id":26804,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts\/11552\/revisions\/26804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/media\/24511"}],"wp:attachment":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/media?parent=11552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/categories?post=11552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/tags?post=11552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}