{"id":11488,"date":"2016-01-20T00:00:00","date_gmt":"2016-01-19T23:00:00","guid":{"rendered":"http:\/\/web-server-devel.mgc.es\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/"},"modified":"2019-11-22T12:43:23","modified_gmt":"2019-11-22T11:43:23","slug":"tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya","status":"publish","type":"post","link":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/","title":{"rendered":"Tornen els aniversaris i els tallers d&#8217;Aloha a les oficines de la M\u00fatua General de Catalunya"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2251\" src=\"https:\/\/www.mgc.es\/wp-content\/uploads\/2016\/01\/espaimutua_estudi.jpg\" alt=\"espaimutua_estudi\" width=\"821\" height=\"442\" \/>Despr\u00e9s de les festes es repr\u00e8n l&#8217;activitat als Espais M\u00fatua. Aquesta setmana han comen\u00e7at els tallers d&#8217;aprenentatge per als nens i nenes, aix\u00ed com els aniversaris per als fills dels mutualistes, a les oficines de la M\u00fatua que disposen d&#8217;Espai M\u00fatua. El 2015 es van celebrar 82 aniversaris, amb m\u00e9s de 2.050 assistents, entre nens i convidats, i es van impartir 118 tallers d&#8217;Aloha.<!--more--><\/p>\n<p>Aloha Mental Arithmetic \u00e9s un m\u00e8tode innovador que contribueix al desenvolupament mental dels nens i estimula les seves habilitats anal\u00edtiques i creatives, alhora que complementa la perfecci\u00f3 el seu desenvolupament escolar. Els nens obtenen un benefici notable en el desenvolupament de la seva intel\u00b7lig\u00e8ncia global i els beneficis i resultats s&#8217;aprecien en especial en el c\u00e0lcul mental i la seva agilitat per realitzar-lo. Hem anat incrementant els tallers per als nens i nenes mutualistes a les oficines que hem inaugurat arreu de Catalunya.<\/p>\n<p>En total s\u00f3n 18 les que ofereixen els tallers gratu\u00efts als que, al llarg d&#8217;aquests darrers dos anys s&#8217;han apuntat un gran nombre d&#8217;infants (Barcelona, Sant Cugat, Sabadell, Granollers, Matar\u00f3, Igualada, Vic, Manresa, Vilanova, Girona, Figueres, Blanes, Palam\u00f3s, Tarragona, Tortosa, Reus, Lleida i Palma de Mallorca).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despr\u00e9s de les festes es repr\u00e8n l&#8217;activitat als Espais M\u00fatua. Aquesta setmana han comen\u00e7at els tallers d&#8217;aprenentatge per als nens i nenes, aix\u00ed com els aniversaris per als fills dels mutualistes, a les oficines de la M\u00fatua que disposen d&#8217;Espai M\u00fatua. El 2015 es van celebrar 82 aniversaris, amb m\u00e9s de 2.050 assistents, entre nens [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-11488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat"],"featured_image_src":"https:\/\/www.mgc.es\/wp-content\/uploads\/2019\/11\/espaimutua_estudi.jpg","author_info":{"display_name":"Revista Inter\u00e8s Mutu","author_link":"https:\/\/www.mgc.es\/ca\/blog\/author\/interesmutu\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tornen els aniversaris i els tallers d&#039;Aloha a les oficines de la M\u00fatua General de Catalunya - MGC M\u00fatua<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tornen els aniversaris i els tallers d&#039;Aloha a les oficines de la M\u00fatua General de Catalunya - MGC M\u00fatua\" \/>\n<meta property=\"og:description\" content=\"Despr\u00e9s de les festes es repr\u00e8n l&#8217;activitat als Espais M\u00fatua. Aquesta setmana han comen\u00e7at els tallers d&#8217;aprenentatge per als nens i nenes, aix\u00ed com els aniversaris per als fills dels mutualistes, a les oficines de la M\u00fatua que disposen d&#8217;Espai M\u00fatua. El 2015 es van celebrar 82 aniversaris, amb m\u00e9s de 2.050 assistents, entre nens [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/\" \/>\n<meta property=\"og:site_name\" content=\"MGC M\u00fatua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mgcmutua\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-19T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-22T11:43:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mgc.es\/wp-content\/uploads\/2019\/11\/espaimutua_estudi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"821\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Revista Inter\u00e8s Mutu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mgcmutua\" \/>\n<meta name=\"twitter:site\" content=\"@mgcmutua\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Revista Inter\u00e8s Mutu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tornen els aniversaris i els tallers d'Aloha a les oficines de la M\u00fatua General de Catalunya - MGC M\u00fatua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/","og_locale":"ca_ES","og_type":"article","og_title":"Tornen els aniversaris i els tallers d'Aloha a les oficines de la M\u00fatua General de Catalunya - MGC M\u00fatua","og_description":"Despr\u00e9s de les festes es repr\u00e8n l&#8217;activitat als Espais M\u00fatua. Aquesta setmana han comen\u00e7at els tallers d&#8217;aprenentatge per als nens i nenes, aix\u00ed com els aniversaris per als fills dels mutualistes, a les oficines de la M\u00fatua que disposen d&#8217;Espai M\u00fatua. El 2015 es van celebrar 82 aniversaris, amb m\u00e9s de 2.050 assistents, entre nens [&hellip;]","og_url":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/","og_site_name":"MGC M\u00fatua","article_publisher":"https:\/\/www.facebook.com\/mgcmutua","article_published_time":"2016-01-19T23:00:00+00:00","article_modified_time":"2019-11-22T11:43:23+00:00","og_image":[{"width":821,"height":442,"url":"https:\/\/www.mgc.es\/wp-content\/uploads\/2019\/11\/espaimutua_estudi.jpg","type":"image\/jpeg"}],"author":"Revista Inter\u00e8s Mutu","twitter_card":"summary_large_image","twitter_creator":"@mgcmutua","twitter_site":"@mgcmutua","twitter_misc":{"Escrit per":"Revista Inter\u00e8s Mutu","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#article","isPartOf":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/"},"author":{"name":"Revista Inter\u00e8s Mutu","@id":"https:\/\/www.mgc.es\/#\/schema\/person\/010c961d9c9acf38f11187a02b646c16"},"headline":"Tornen els aniversaris i els tallers d&#8217;Aloha a les oficines de la M\u00fatua General de Catalunya","datePublished":"2016-01-19T23:00:00+00:00","dateModified":"2019-11-22T11:43:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/"},"wordCount":220,"commentCount":0,"publisher":{"@id":"https:\/\/www.mgc.es\/#organization"},"image":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2019\/11\/espaimutua_estudi.jpg","articleSection":["Actualitat M\u00fatua"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/","url":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/","name":"Tornen els aniversaris i els tallers d'Aloha a les oficines de la M\u00fatua General de Catalunya - MGC M\u00fatua","isPartOf":{"@id":"https:\/\/www.mgc.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#primaryimage"},"image":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2019\/11\/espaimutua_estudi.jpg","datePublished":"2016-01-19T23:00:00+00:00","dateModified":"2019-11-22T11:43:23+00:00","breadcrumb":{"@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#primaryimage","url":"https:\/\/www.mgc.es\/wp-content\/uploads\/2019\/11\/espaimutua_estudi.jpg","contentUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2019\/11\/espaimutua_estudi.jpg","width":821,"height":442},{"@type":"BreadcrumbList","@id":"https:\/\/www.mgc.es\/ca\/blog\/tornen-els-aniversaris-i-els-tallers-daloha-a-les-oficines-de-la-mutua-general-de-catalunya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mgc.es\/ca\/"},{"@type":"ListItem","position":2,"name":"Tornen els aniversaris i els tallers d&#8217;Aloha a les oficines de la M\u00fatua General de Catalunya"}]},{"@type":"WebSite","@id":"https:\/\/www.mgc.es\/#website","url":"https:\/\/www.mgc.es\/","name":"MGC M\u00fatua","description":"MGC M\u00fatua \u00e9s una entitat asseguradora sense \u00e0nim de lucre constitu\u00efda al 1982 i especialitzada en assegurances de salut i assist\u00e8ncia.","publisher":{"@id":"https:\/\/www.mgc.es\/#organization"},"alternateName":"MGC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mgc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.mgc.es\/#organization","name":"MGC Mutua","alternateName":"MGC","url":"https:\/\/www.mgc.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.mgc.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.mgc.es\/wp-content\/uploads\/2020\/03\/mgcmutua_h2_2t_reduccions.png","contentUrl":"https:\/\/www.mgc.es\/wp-content\/uploads\/2020\/03\/mgcmutua_h2_2t_reduccions.png","width":303,"height":165,"caption":"MGC Mutua"},"image":{"@id":"https:\/\/www.mgc.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mgcmutua","https:\/\/x.com\/mgcmutua","https:\/\/www.youtube.com\/c\/MGCMutua"]},{"@type":"Person","@id":"https:\/\/www.mgc.es\/#\/schema\/person\/010c961d9c9acf38f11187a02b646c16","name":"Revista Inter\u00e8s Mutu","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/52302d684339b9d7bf5691e2ad00835d62ce3b4a435f21ca9f21fbe39c63cb1b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52302d684339b9d7bf5691e2ad00835d62ce3b4a435f21ca9f21fbe39c63cb1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52302d684339b9d7bf5691e2ad00835d62ce3b4a435f21ca9f21fbe39c63cb1b?s=96&d=mm&r=g","caption":"Revista Inter\u00e8s Mutu"}}]}},"_links":{"self":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts\/11488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/comments?post=11488"}],"version-history":[{"count":1,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts\/11488\/revisions"}],"predecessor-version":[{"id":15005,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/posts\/11488\/revisions\/15005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/media\/13841"}],"wp:attachment":[{"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/media?parent=11488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/categories?post=11488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mgc.es\/ca\/wp-json\/wp\/v2\/tags?post=11488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}